{"id":462115,"date":"2023-10-11T22:41:45","date_gmt":"2023-10-12T05:41:45","guid":{"rendered":"https:\/\/www.jefebet.com\/?p=462115"},"modified":"2023-10-11T22:41:51","modified_gmt":"2023-10-12T05:41:51","slug":"pereira-vs-la-equidad-predicciones-pronostico-cuotas-y-previa-de-apuestas-para-la-jornada-17-del-clausura-2023-de-liga-colombiana-el-14-de-octubre","status":"publish","type":"post","link":"https:\/\/blog.jefebet.com\/es\/noticias\/futbol\/liga-colombiana\/pereira-vs-la-equidad-predicciones-pronostico-cuotas-y-previa-de-apuestas-para-la-jornada-17-del-clausura-2023-de-liga-colombiana-el-14-de-octubre\/","title":{"rendered":"Pereira vs La Equidad: Predicciones, pron\u00f3stico, cuotas y previa de apuestas para la jornada 17 del Clausura 2023 de Liga Colombiana el 14 de octubre"},"content":{"rendered":"\n<p><strong>Pereira vs La Equidad<\/strong>, dos equipos necesitados de puntos, y tambi\u00e9n de un milagro, se enfrentan este proximo s\u00e1bado por la jornada 17 del Clausura 2023 de <a href=\"https:\/\/blog.jefebet.com\/noticias\/futbol\/liga-colombiana\/\">la Liga Colombiana<\/a>. <\/p>\n\n\n\n<p><em>El Grande Mateca\u00f1a<\/em> sum\u00f3 un nuevo empate a su lista <strong><a href=\"https:\/\/blog.jefebet.com\/noticias\/futbol\/liga-colombiana\/pereira-vs-aguilas-doradas-predicciones-pronostico-cuotas-y-previa-de-apuestas-para-la-jornada-8-del-clausura-2023-de-liga-colombiana-el-11-de-octubre\/\">tras igualar como locales, por 0-0, con \u00c1guilas Doradas<\/a><\/strong>, mientras que <em>los Aseguradores<\/em> consiguieron <strong><a href=\"https:\/\/blog.jefebet.com\/noticias\/futbol\/liga-colombiana\/la-equidad-vs-deportivo-pasto-predicciones-pronostico-cuotas-y-previa-de-apuestas-para-la-jornada-16-del-clausura-2023-de-liga-colombiana-el-8-de-octubre\/\">un gran triunfo en casa, ante Deportivo Pasto, con pizarra de 1-0<\/a><\/strong>. <\/p>\n\n\n\n<p>Sin m\u00e1s pre\u00e1mbulos, en\u00a0<strong>JefeBet<\/strong>\u00a0te traemos la mejor previa del partido entre Pereira vs La Equidad, duelo que adem\u00e1s\u00a0<strong><a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">viene cargado con el mejor bono de bienvenida por parte de Codere<\/a><\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n<p>[the_ad_placement id=\u00bbarticles-caliente\u00bb]<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n<p>[the_ad_placement id=\u00bbarticles-codere-sportsbook\u00bb]<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n<p>[the_ad_placement id=\u00bbarticles-codere-colombia-sports\u00bb]<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n<p>[the_ad_placement id=\u00bbarticles-draftkings\u00bb]<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pron\u00f3stico, predicciones, cuotas y previa de apuestas para el partido entre&nbsp;Pereira vs La Equidad en la jornada 17 del Clausura 2023 de la&nbsp;Liga Colombiana el 14 de octubre<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00f3nde:&nbsp;<\/strong>Estadio Hern\u00e1n Ram\u00edrez Villegas &#8211; Pereira, Colombia.   <\/li>\n\n\n\n<li><strong>Cu\u00e1ndo:&nbsp;<\/strong>S\u00e1bado, 14 de octubre de 2023, 5:00 PM E.T.<\/li>\n\n\n\n<li><strong>Moneyline:<\/strong> Pereira (<a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">+120<\/a>) \/ Empate (<a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">+225<\/a>) \/ La Equidad (<a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">+245<\/a>).<\/li>\n\n\n\n<li><strong>Over\/Under (2.5):<\/strong>&nbsp;Over (<a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">+120<\/a>) \/ Under (<a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">-139<\/a>).<\/li>\n\n\n\n<li><strong>Ambos equipos marcan:<\/strong>\u00a0S\u00ed (<a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">-125<\/a>) \/ No (<a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">-106<\/a>). <\/li>\n<\/ul>\n\n\n\n<p><em>Todas las cuotas mostradas son cortes\u00eda de&nbsp;<a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">Codere.<\/a><\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La previa de Pereira (<a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">+120 en Codere<\/a>)<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-1024x576.jpg\" alt=\"Pereira vs La Equidad: Predicciones, pron\u00f3stico, cuotas y previa de apuestas para la jornada 17 del Clausura 2023 de Liga Colombiana el 14 de octubre\" class=\"wp-image-462290\" srcset=\"https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-1024x576.jpg 1024w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-300x169.jpg 300w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-768x432.jpg 768w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-1536x864.jpg 1536w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-2048x1152.jpg 2048w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-192x108.jpg 192w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-384x216.jpg 384w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-364x205.jpg 364w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-728x409.jpg 728w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-561x316.jpg 561w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-1122x631.jpg 1122w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-265x149.jpg 265w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-531x299.jpg 531w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-608x342.jpg 608w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-758x426.jpg 758w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-1152x648.jpg 1152w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-85x48.jpg 85w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-1-171x96.jpg 171w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Deportivo Pereira pr\u00e1cticamente le dijo adi\u00f3s al cuadrangular final del torneo Clausura luego de no poder pasar este mi\u00e9rcoles de un empate 0-0, ante el l\u00edder \u00c1guilas Doradas, en un compromiso reprogramado de la jornada 8. <\/p>\n\n\n\n<p><em>El Grande Mateca\u00f1a <\/em><strong>apenas suma dos victorias en sus \u00faltimos nueve partidos<\/strong> y ese rendimiento lo hizo bajar hasta el puesto# 18 con 16 unidades, a siete unidades del \u00faltimo cupo para el cuadrangular final y con nueve equipos por delante a falta de tres fechas para que termine el campeonato. <\/p>\n\n\n\n<p>Si bien en sus pasados ocho encuentros anotaron al menos en seis, la inconsistencia le volvi\u00f3 a pasar factura a Pereira, quien adem\u00e1s es el segundo peor conjunto de la liga jugando como local con apenas ocho puntos de 24 posibles y <strong>solo un triunfo en sus \u00faltimos cinco duelos en esta condici\u00f3n<\/strong>. <\/p>\n\n\n\n<p><strong>Alineaci\u00f3n probable (3-5-2):<\/strong>&nbsp;Aldair Quintana; Carlos Garc\u00e9s, Kener Valencia, Yeison Su\u00e1rez; Jordy Ararat, Ewil Murillo, Juan Zuluaga, Diego Hern\u00e1ndez, Maicol Medina; Eber Moreno, Alejandro Piedrahita.<\/p>\n\n\n\n<div class=\"wp-block-my-teams-block-my-teams-block\"><span class=\"dashicons dashicons-calculator\"><\/span>You need to configure the Teams and Odds to be able to visualize correctly the Call Odds Teams Block Component.<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La previa de La Equidad (<a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">+245 en Codere<\/a>)<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-1024x576.jpg\" alt=\"Pereira vs La Equidad: Predicciones, pron\u00f3stico, cuotas y previa de apuestas para la jornada 17 del Clausura 2023 de Liga Colombiana el 14 de octubre\" class=\"wp-image-462292\" srcset=\"https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-1024x576.jpg 1024w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-300x169.jpg 300w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-768x432.jpg 768w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-1536x864.jpg 1536w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-2048x1152.jpg 2048w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-192x108.jpg 192w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-384x216.jpg 384w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-364x205.jpg 364w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-728x409.jpg 728w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-561x316.jpg 561w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-1122x631.jpg 1122w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-265x149.jpg 265w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-531x299.jpg 531w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-608x342.jpg 608w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-758x426.jpg 758w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-1152x648.jpg 1152w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-85x48.jpg 85w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/pereira-vs-la-equidad-2-171x96.jpg 171w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La situaci\u00f3n de La Equidad no es tan delicada como la de Pereira, pero con tan pocas jornadas por disputar su clasificaci\u00f3n no depende solo de ellos sino de un conglomerado de resultados. <\/p>\n\n\n\n<p>A pesar de que <em>los Aseguradores<\/em> apenas suman tres derrotas en la campa\u00f1a, <strong>estos son l\u00edderes en encuentros empatados con 10<\/strong>. Dicho accionar los tiene en la plaza #13 con 19 puntos, cuatro por debajo de Santa Fe en el \u00faltimo cupo al cuadrangular final. <\/p>\n\n\n\n<p>El problema de La Equidad es que apenas registra 13 goles anotados en 16 choques disputados y nunca anot\u00f3 m\u00e1s de dos tantos en un partido. Eso s\u00ed, como visitante tiene siete de esos goles, peros <strong>sus \u00fanicas tres derrotas llegaron en la carretera y solo consigui\u00f3 un triunfo en ocho partidos<\/strong>. <\/p>\n\n\n\n<p>Sin embargo, en feudo ajeno tambi\u00e9n empat\u00f3 en cuatro oportunidades, resultado que es muy probable se repita en esta oportunidad y por lo que te recomendamos ir a <strong><a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">Codere<\/a><\/strong> a jugar el Handicap (+1) de la visita, <strong><a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">l\u00ednea que se ubica en (-154) y con la que podr\u00e1s ganar hasta 64$ por cada 100$ apostados si se da un empate o una victoria de La Equidad<\/a><\/strong>. <\/p>\n\n\n\n<p><strong>Alineaci\u00f3n probable (4-2-3-1):<\/strong>&nbsp;Washington Ortega; Daniel Polanco, Joan Castro, Mart\u00edn Payares, Andr\u00e9s Correa; Felipe Acosta, Pablo Lima; David Camacho, Johan Rojas, Francisco Chaverra; Jos\u00e9 Lloreda.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong><strong><strong><strong>Predicci\u00f3n de JefeBet<\/strong><\/strong><\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p>Si algo debemos de estar seguros para este encuentro es que no deber\u00edamos de estar en presencia de un festival de goles en Pereira. <\/p>\n\n\n\n<p>De por vida, los choques entre estos clubes nos han regalado compromisos con pizarras de pocas anotaciones y su producci\u00f3n ofensiva de esta campa\u00f1a no nos augura algo distinto. <\/p>\n\n\n\n<p>Siete de sus \u00faltimos diez enfrentamientos terminaron con dos tantos o menos en el marcador, aunque en casa de Pereira, donde han jugado en ocho oportunidades, la pizarra termin\u00f3 con tres goles o m\u00e1s en cinco ocasiones. <\/p>\n\n\n\n<p>Dicho esto, en <strong>JefeBet<\/strong> te aconsejamos ir a <strong><a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">Codere<\/a><\/strong> para jugar el Under del encuentro, <strong><a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">una l\u00ednea que se ubica en (-139) y que te har\u00e1 ganar hasta 72$ por cada 100$ apostados<\/a><\/strong>. <\/p>\n\n\n\n<p><strong>Predicci\u00f3n:<\/strong> Under (PER 1 &#8211; LEQ 1) | <strong><a href=\"https:\/\/online.codere.com.co\/promoRedirect?key=ej0xMzUzMDA0OCZsPTEzNTk3MjE5JnA9MzA5NzU1\" target=\"_blank\" rel=\"noreferrer noopener\">Apuesta aqu\u00ed por el Under del partido<\/a><\/strong>. <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong><strong>Apuesta a la predicci\u00f3n anterior o la de tu preferencia, y consigue un bonus instant\u00e1neo gratis haciendo click en el banner debajo de este texto<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h4>\n\n\n\n<p>Oferta para Residentes en M\u00e9xico:<\/p>\n\n\n<p>[the_ad_placement id=\u00bbarticles-caliente\u00bb]<\/p>\n\n\n<p>[the_ad_placement id=\u00bbarticles-codere-sportsbook\u00bb]<\/p>\n\n\n\n<p>Oferta para Residentes en Chile:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/jefenewsletter.com\/sorteo-fiesta-de-swag\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"500\" height=\"90\" src=\"https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/75aa44d8-e1f8-4d47-83c7-6933a0357209-2.jpg\" alt=\"\" class=\"wp-image-462116\" srcset=\"https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/75aa44d8-e1f8-4d47-83c7-6933a0357209-2.jpg 500w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/75aa44d8-e1f8-4d47-83c7-6933a0357209-2-300x54.jpg 300w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/75aa44d8-e1f8-4d47-83c7-6933a0357209-2-265x48.jpg 265w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/75aa44d8-e1f8-4d47-83c7-6933a0357209-2-364x66.jpg 364w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2023\/10\/75aa44d8-e1f8-4d47-83c7-6933a0357209-2-267x48.jpg 267w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/figure><\/div>\n\n\n<p>Oferta para Residentes en Colombia:<\/p>\n\n\n<p>[the_ad_placement id=\u00bbarticles-codere-colombia-sports\u00bb]<\/p>\n\n\n\n<p>Oferta para Residentes en USA:<\/p>\n\n\n<p>[the_ad_placement id=\u00bbarticles-draftkings\u00bb]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pereira vs La Equidad, dos equipos necesitados de puntos, y tambi\u00e9n de un milagro, se enfrentan este proximo s\u00e1bado por la jornada 17 del Clausura 2023 de la Liga Colombiana. El Grande Mateca\u00f1a sum\u00f3 un nuevo empate a su lista tras igualar como locales, por 0-0, con \u00c1guilas Doradas, mientras que los Aseguradores consiguieron un [&hellip;] <a class=\"g1-link g1-link-more\" href=\"https:\/\/blog.jefebet.com\/es\/noticias\/futbol\/liga-colombiana\/pereira-vs-la-equidad-predicciones-pronostico-cuotas-y-previa-de-apuestas-para-la-jornada-17-del-clausura-2023-de-liga-colombiana-el-14-de-octubre\/\">More<\/a><\/p>\n","protected":false},"author":15,"featured_media":462288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[52407,37873,37,274,37872],"tags":[43465],"reaction":[],"class_list":{"0":"post-462115","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-liga-colombiana","8":"category-estados-unidos","9":"category-futbol","10":"category-noticias","11":"category-pais","12":"tag-liga-colombiana"},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts\/462115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/comments?post=462115"}],"version-history":[{"count":0,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts\/462115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/media\/462288"}],"wp:attachment":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/media?parent=462115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/categories?post=462115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/tags?post=462115"},{"taxonomy":"reaction","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/reaction?post=462115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}