{"id":49673,"date":"2022-04-26T20:13:21","date_gmt":"2022-04-27T03:13:21","guid":{"rendered":"http:\/\/54.208.119.128\/sin-categorizar\/eddie-rosario-bravos\/"},"modified":"2022-04-26T20:13:21","modified_gmt":"2022-04-27T03:13:21","slug":"eddie-rosario-bravos","status":"publish","type":"post","link":"https:\/\/blog.jefebet.com\/es\/noticias\/beisbol\/eddie-rosario-bravos\/","title":{"rendered":"LAMENTABLE: Eddie Rosario se perder\u00e1 gran parte de la temporada con los Bravos"},"content":{"rendered":"\n<p>Los Bravos de Atlanta no est\u00e1n teniendo su mejor inicio de temporada en las <a href=\"https:\/\/blog.jefebet.com\/noticias\/beisbol\/\" target=\"_blank\" rel=\"noreferrer noopener\">Grandes Ligas<\/a> y adem\u00e1s tendr\u00e1n que lidiar con la ausencia del jardinero <a href=\"https:\/\/www.baseball-reference.com\/players\/r\/rosared01.shtml\" target=\"_blank\" rel=\"noreferrer noopener\">Eddie Rosario<\/a> debido a una operaci\u00f3n que se someter\u00e1 a finales de esta semana. <\/p>\n\n\n\n<p>Seg\u00fan dio a conocer el mismo equipo a trav\u00e9s de sus redes sociales, el puertorrique\u00f1o vio el lunes a un especialista en retina y se someter\u00e1 a un procedimiento con l\u00e1ser en los pr\u00f3ximos d\u00edas para corregir la visi\u00f3n borrosa y la hinchaz\u00f3n en su ojo derecho.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Medical Update on Eddie Rosario:<br><br>OF Eddie Rosario saw a retinal specialist today and will undergo a laser procedure in the coming days to correct blurred vision and swelling in his right eye.<\/p>&mdash; Atlanta Braves (@Braves) <a href=\"https:\/\/twitter.com\/Braves\/status\/1518778209743032320?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 26, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Si bien los Bravos agregaron que en los pr\u00f3ximos d\u00edas dar\u00e1n a conocer m\u00e1s detalles sobre el tiempo que estar\u00e1 fuera de acci\u00f3n Eddie Rosario, el periodista Justin Toscano, del Atlanta Jounal-Constitution, destac\u00f3 que podr\u00eda estar fuera de ocho a doce semanas, tiempo que se estipula pertinente para recuperarse de este tipo de procedimiento cl\u00ednico. <\/p>\n\n\n\n<p>Eddie Rosario hab\u00eda tenido un lento comienzo de temporada en el caj\u00f3n de bateo adem\u00e1s de varios inconvenientes para atrapar la pelota en los jardines, por lo que este problema en su visi\u00f3n podr\u00eda dar respuestas mucho m\u00e1s claro al porqu\u00e9 de su bajo rendimiento. <\/p>\n\n\n\n<p>En 44 veces al bate el guardabosque solo conect\u00f3 tres imparables, uno de ellos doblete, para promediar .068. En 15 juegos se ponch\u00f3 en 10 ocasiones, recibi\u00f3 cinco boletos y su OBP era de apenas .163. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The Braves have a very valid reason for Eddie Rosario&#39;s struggles: He could not see properly. <br><br>A loose estimate is that he misses eight to 12 weeks. <a href=\"https:\/\/t.co\/oWJnrKQyXP\">https:\/\/t.co\/oWJnrKQyXP<\/a><\/p>&mdash; Justin Toscano (@JustinCToscano) <a href=\"https:\/\/twitter.com\/JustinCToscano\/status\/1518784094276050947?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 26, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>N\u00fameros muy por debajo del promedio de Eddie Rosario que seguramente llevaron a los Bravos a realizar algunas pruebas para buscar respuestas al rendimiento del jugador que firm\u00f3, previo a esta campa\u00f1a, un contrato con la organizaci\u00f3n por dos temporadas y 18 millones de d\u00f3lares. <\/p>\n\n\n\n<p>Vale recordar que Rosario lleg\u00f3 la temporada pasada a Atlanta en un cambio que envi\u00f3 a Pablo Sandoval a los Indios de Cleveland. En definitiva disput\u00f3 33 compromisos con los Bravos, pero su mayor aporte lleg\u00f3 en la postemporada, instancia en la que en 16 compromisos dej\u00f3 una impresionante linea ofensiva de .383\/.456\/.617 con tres jonrones, 11 carreras impulsadas y un reconocimiento como el Jugador M\u00e1s Valioso de la Serie de Campeonato de la Liga Nacional ante Los Dodgers de Los Angeles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Movimientos en los jardines tras la ausencia de Eddie Rosario<\/h2>\n\n\n\n<p>La imprevista ausencia de Eddie Rosario por la operaci\u00f3n a la que deber\u00e1 ser sometido, adem\u00e1s del lento inicio de 7-10 que han tenido los Bravos de Atlanta en la que promete ser\u00e1 una peleada Divisi\u00f3n Este de la Liga Nacional, podr\u00eda impulsar a los actuales campeones de las Grandes Ligas a apurar el regreso de Ronald Acu\u00f1a Jr. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Eddie Rosario will be on the shelf for a while. <a href=\"https:\/\/twitter.com\/hashtag\/Braves?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Braves<\/a> have Ronald Acu\u00f1a Jr. nearing return \u2013 which already felt to be on track to happen before the original May 6 target date. Can&#39;t imagine this news does anything but strengthen his chances of returning sooner than later. <a href=\"https:\/\/t.co\/KXnFaYBRmF\">https:\/\/t.co\/KXnFaYBRmF<\/a><\/p>&mdash; Grant McAuley (@grantmcauley) <a href=\"https:\/\/twitter.com\/grantmcauley\/status\/1518779154640130050?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 26, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>El jardinero venezolano est\u00e1 pautado para jugar siete episodios el mi\u00e9rcoles en Triple A y nueve innings el jueves, teniendo como fecha tentativa de regreso al equipo grande el pr\u00f3ximo 6 de mayo. Sin embargo, debido a los problemas ofensivos del equipo y la ausencia del puertorrique\u00f1o, dicha fecha podr\u00eda ser adelantada. <\/p>\n\n\n\n<p>Por ahora los Bravos quedar\u00e1n bastante comprometidos en los jardines al tener que usar a Marcell Ozuna todos los d\u00edas en el jard\u00edn izquierdo, una situaci\u00f3n un tanto arriesgada ya que el dominicano no es conocido por sus buenas artes defensivas. En el jard\u00edn central tendr\u00e1n a Adam Duvall, mientras que en el jard\u00edn derecho contar\u00e1n con Guillermo Heredia. Travis Demeritte ser\u00e1 el cuarto jardinero y el venezolano Orlando Arcia el infielder de emergencia para los jardines. <\/p>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Bravos de Atlanta no est\u00e1n teniendo su mejor inicio de temporada en las Grandes Ligas y adem\u00e1s tendr\u00e1n que lidiar con la ausencia del jardinero Eddie Rosario debido a una operaci\u00f3n que se someter\u00e1 a finales de esta semana. Seg\u00fan dio a conocer el mismo equipo a trav\u00e9s de sus redes sociales, el puertorrique\u00f1o [&hellip;] <a class=\"g1-link g1-link-more\" href=\"https:\/\/blog.jefebet.com\/es\/noticias\/beisbol\/eddie-rosario-bravos\/\">More<\/a><\/p>\n","protected":false},"author":15,"featured_media":49677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[38,437,274],"tags":[20423,20424,435,488,439],"reaction":[],"class_list":{"0":"post-49673","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-beisbol","8":"category-lo-ultimo","9":"category-noticias","10":"tag-atlanta-braves","11":"tag-bravos-de-atlanta","12":"tag-grandes-ligas","13":"tag-las-mayores","14":"tag-mlb"},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts\/49673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/comments?post=49673"}],"version-history":[{"count":0,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts\/49673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/media\/49677"}],"wp:attachment":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/media?parent=49673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/categories?post=49673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/tags?post=49673"},{"taxonomy":"reaction","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/reaction?post=49673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}