{"id":50117,"date":"2022-04-28T21:38:52","date_gmt":"2022-04-29T04:38:52","guid":{"rendered":"http:\/\/54.208.119.128\/sin-categorizar\/ronald-acuna-jr-regreso\/"},"modified":"2022-04-28T21:38:52","modified_gmt":"2022-04-29T04:38:52","slug":"ronald-acuna-jr-regreso","status":"publish","type":"post","link":"https:\/\/blog.jefebet.com\/es\/noticias\/beisbol\/ronald-acuna-jr-regreso\/","title":{"rendered":"Ronald Acu\u00f1a Jr. regres\u00f3 a la acci\u00f3n tras nueve meses de recuperaci\u00f3n"},"content":{"rendered":"\n<p>La larga espera por volver a ver a <a href=\"https:\/\/www.baseball-reference.com\/players\/a\/acunaro01.shtml\" target=\"_blank\" rel=\"noreferrer noopener\">Ronald Acu\u00f1a Jr.<\/a> en un terreno de juego termin\u00f3 este jueves, luego de que los Bravos de Atlanta activaran al jardinero venezolano desde la lista de lesionados. <\/p>\n\n\n\n<p>Seg\u00fan inform\u00f3 el mismo equipo a trav\u00e9s de su equipo de prensa, Acu\u00f1a Jr, fue llamado desde el Gwinnett, filial Triple A de Atlanta, donde estaba viendo acci\u00f3n como parte de su proceso de rehabilitaci\u00f3n debido a una rotura de ligamentos cruzados de la rodilla derecha que sufri\u00f3 a mediados de la pasada temporada y que lo dej\u00f3 fuera de acci\u00f3n por nueve meses. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The <a href=\"https:\/\/twitter.com\/hashtag\/Braves?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Braves<\/a> today returned OF Ronald Acu\u00f1a Jr. from his rehabilitation assignment and reinstated him from the 10-day injured list. To make room on the active roster, the club designated OF Alex Dickerson for assignment.<\/p>&mdash; Atlanta Braves (@Braves) <a href=\"https:\/\/twitter.com\/Braves\/status\/1519659515834253312?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 28, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>El estelar jardinero fungir\u00e1 como primer bate y jardinero derecho del equipo que dirige Brian Snitker, intentado despertar a un equipo que no ha tenido su mejor comienzo de campa\u00f1a tras ganar la Serie Mundial del a\u00f1o pasado. <\/p>\n\n\n\n<p>Si bien el regreso de Ronald Acu\u00f1a Jr. estaba pautado para la pr\u00f3xima semana, la operaci\u00f3n a la cual se deber\u00e1 someter <a href=\"https:\/\/blog.jefebet.com\/beisbol\/eddie-rosario-bravos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Eddie Rosario en el ojo derecho<\/a>, y que lo dejar\u00e1 fuera por casi dos meses, seguramente propici\u00f3 que la gerencia y el cuerpo t\u00e9cnico adelantaran el regreso del guardabosques. <\/p>\n\n\n\n<p>De igual manera se pudo conocer que los Bravos planean darle tambi\u00e9n tiempo de juego a Acu\u00f1a Jr. como bateador designado, esto mientras su cuerpo se recupera completamente de tanto tiempo sin ver acci\u00f3n al m\u00e1ximo nivel de competencia. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">\ud835\ude09\ud835\ude22\ud835\ude35\ud835\ude35\ud835\ude2a\ud835\ude2f\ud835\ude28 \ud835\ude2d\ud835\ude26\ud835\ude22\ud835\ude25\ud835\ude30\ud835\ude27\ud835\ude27 \ud835\ude22\ud835\ude2f\ud835\ude25 \ud835\ude31\ud835\ude2d\ud835\ude22\ud835\ude3a\ud835\ude2a\ud835\ude2f\ud835\ude28 \ud835\ude33\ud835\ude2a\ud835\ude28\ud835\ude29\ud835\ude35 \ud835\ude27\ud835\ude2a\ud835\ude26\ud835\ude2d\ud835\ude25&#8230; <a href=\"https:\/\/t.co\/hiiwBT23A8\">pic.twitter.com\/hiiwBT23A8<\/a><\/p>&mdash; Bally Sports: Braves (@BravesOnBally) <a href=\"https:\/\/twitter.com\/BravesOnBally\/status\/1519760080396242945?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 28, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>En esta posici\u00f3n compartir\u00e1 tiempo de juego con Marcell Ozuna, el dominicano que no es reconocido por su defensa y que hab\u00eda aprovechado la implementaci\u00f3n del bateador designado en la Liga Nacional para tomar algunos turnos en este rol. <\/p>\n\n\n\n<p>Adem\u00e1s de su regreso, los Bravos est\u00e1n entusiasmados con lo hecho por Ronald Acu\u00f1a Jr. en su breve paso por las menores, ya que este luci\u00f3 bien f\u00edsicamente y no desluci\u00f3 a la ofensiva al batear de 19-7 con seis boletos y seis ponches. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un repaso a la trayector\u00eda de Ronald Acu\u00f1a Jr.<\/strong><\/h2>\n\n\n\n<p>En 2018 Acu\u00f1a Jr. debut\u00f3 con Atlanta en las Grandes Ligas y se alz\u00f3 con el premio al Novato del A\u00f1o de la Nacional. Desde su llegada al circuito no ha dejado de ser un verdadero espect\u00e1culo y muestra de ello es que la campa\u00f1a pasada, antes de lesionarse, llevaba n\u00fameros dignos de un MVP al conectar 24 jonrones y remolcar 52 carreras en 82 compromisos disputados. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">\ud835\udc13\ud835\udc07\ud835\udc04 \ud835\udc11\ud835\udc04\ud835\udc13\ud835\udc14\ud835\udc11\ud835\udc0d<a href=\"https:\/\/twitter.com\/ronaldacunajr24?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@ronaldacunajr24<\/a> is back. <a href=\"https:\/\/t.co\/bwyyYtVGDg\">pic.twitter.com\/bwyyYtVGDg<\/a><\/p>&mdash; Bally Sports: Braves (@BravesOnBally) <a href=\"https:\/\/twitter.com\/BravesOnBally\/status\/1519661079370031104?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 28, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Esta ser\u00e1 la quinta campa\u00f1a de Ronald Acu\u00f1a Jr. en Las Mayores, donde adem\u00e1s del Novato del A\u00f1o ha asistido a dos Juegos de Estrellas, ha ganado dos Bates de Plata y en 2019 se convirti\u00f3 en apenas el segundo jugador en la historia de la liga en unirse al club de los 30 jonrones y 30 bases robadas en una misma campa\u00f1a antes de los 22 a\u00f1os de edad junto a Mike Trout. <\/p>\n\n\n\n<p>Veremos si el venezolano es capaz de dejar atr\u00e1s su dura lesi\u00f3n y ayudar a un equipo de Atlanta que no ha comenzado con el pie derecho su defensa del t\u00edtulo. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La larga espera por volver a ver a Ronald Acu\u00f1a Jr. en un terreno de juego termin\u00f3 este jueves, luego de que los Bravos de Atlanta activaran al jardinero venezolano desde la lista de lesionados. Seg\u00fan inform\u00f3 el mismo equipo a trav\u00e9s de su equipo de prensa, Acu\u00f1a Jr, fue llamado desde el Gwinnett, filial [&hellip;] <a class=\"g1-link g1-link-more\" href=\"https:\/\/blog.jefebet.com\/es\/noticias\/beisbol\/ronald-acuna-jr-regreso\/\">More<\/a><\/p>\n","protected":false},"author":15,"featured_media":50121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[38,437,274],"tags":[20423,20424,435,488,439,20471],"reaction":[],"class_list":{"0":"post-50117","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-beisbol","8":"category-lo-ultimo","9":"category-noticias","10":"tag-atlanta-braves","11":"tag-bravos-de-atlanta","12":"tag-grandes-ligas","13":"tag-las-mayores","14":"tag-mlb","15":"tag-ronald-acuna-jr"},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts\/50117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/comments?post=50117"}],"version-history":[{"count":0,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts\/50117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/media\/50121"}],"wp:attachment":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/media?parent=50117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/categories?post=50117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/tags?post=50117"},{"taxonomy":"reaction","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/reaction?post=50117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}