{"id":66200,"date":"2022-06-23T13:07:21","date_gmt":"2022-06-23T20:07:21","guid":{"rendered":"https:\/\/www.jefebet.com\/?p=66200"},"modified":"2022-06-23T14:52:52","modified_gmt":"2022-06-23T21:52:52","slug":"baker-mayfield-nfl","status":"publish","type":"post","link":"https:\/\/blog.jefebet.com\/es\/noticias\/futbol-americano\/nfl\/baker-mayfield-nfl\/","title":{"rendered":"Seahawks siguen bastante interesados en adquirir a Baker Mayfield"},"content":{"rendered":"\n<p>Las puertas siguen m\u00e1s que abiertas para que <a href=\"https:\/\/www.pro-football-reference.com\/players\/M\/MayfBa00.htm\" target=\"_blank\" rel=\"noreferrer noopener\">Baker Mayfield<\/a> pueda llegar en las pr\u00f3ximas semanas a los Seattle Seahawks. <\/p>\n\n\n\n<p>Seg\u00fan un reporte de la periodista Josina Anderson, de CBS Sports HQ, la organizaci\u00f3n <strong>sigue interesada en adquirir los servicios del mariscal de campo<\/strong> proveniente de los Cleveland Browns. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">I\u2019m told the <a href=\"https:\/\/twitter.com\/hashtag\/Seahawks?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Seahawks<\/a> still have a high-level of interest in acquiring QB Baker Mayfield and behind-the-scenes are open to contractually extending him, per league source. I also know that the process of collecting information and insights into Mayfield is still ongoing.<\/p>&mdash; JosinaAnderson (@JosinaAnderson) <a href=\"https:\/\/twitter.com\/JosinaAnderson\/status\/1539734992900820993?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 22, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Anderson agreg\u00f3 en su reporte que los Seahawks tambi\u00e9n tienen pensado ofrecerle una extensi\u00f3n a Baker Mayfield, quien esta campa\u00f1a jugar\u00e1 bajo su \u00faltimo a\u00f1o de contrato de novato y percibir\u00e1 18.9 millones de d\u00f3lares con los Browns. <\/p>\n\n\n\n<p>Tras la llegada de Deshaun Watson a Cleveland, el joven quarterback <a href=\"https:\/\/blog.jefebet.com\/noticias\/futbol-americano\/nfl\/baker-mayfield-browns-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">se sinti\u00f3 traicionado<\/a> por su actual organizaci\u00f3n y fue <a href=\"https:\/\/blog.jefebet.com\/noticias\/futbol-americano\/nfl\/baker-mayfield-out\/\" target=\"_blank\" rel=\"noreferrer noopener\">relegado al rol de suplente<\/a> a la espera de que el equipo pueda hacer efectiva su solicitud de cambio. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1.jpg\" alt=\"Baker Mayfield\" class=\"wp-image-66257\" srcset=\"https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1.jpg 1024w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-300x200.jpg 300w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-768x512.jpg 768w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-180x120.jpg 180w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-561x374.jpg 561w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-265x177.jpg 265w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-531x354.jpg 531w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-364x243.jpg 364w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-728x486.jpg 728w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-608x406.jpg 608w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-758x506.jpg 758w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-72x48.jpg 72w, https:\/\/blog.jefebet.com\/wp-content\/uploads\/2022\/06\/baker-mayfield-2-1-144x96.jpg 144w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>A pesar de que Seattle ha dicho en varias ocasiones que, tras la salida de Russell Wilson, se sienten c\u00f3modos con Drew Lock y Geno Smith como su dupla de quarterbacks para la pr\u00f3xima campa\u00f1a, tambi\u00e9n es cierto que el equipo ha estado inmerso en varios rumores relacionados a QB con un poco m\u00e1s de experiencia como es el caso de Baker Mayfield. <\/p>\n\n\n\n<p>Por eso no suena descabellado pensar que el jugador de 27 a\u00f1os de edad pueda llegar a reforzar al equipo de la costa oeste, aunque todav\u00eda no queda claro si los Carolina Panthers tambi\u00e9n seguir\u00e1n en la lucha por \u00e9l. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Los problemas f\u00edsicos de Baker Mayfield<\/strong><\/h2>\n\n\n\n<p>Aunado al alto precio que los Browns piden por Baker Mayfield, otro de los motivos que genera duda sobre el mariscal de campo es tener que pagar una suma muy alta en dinero y picks a sabiendas de los problemas f\u00edsicos que present\u00f3 la temporada pasada. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">\u201cBaker Mayfield has the legs. He has the vision. He has the big play ability with his arm.&quot; This could be the perfect fit for the <a href=\"https:\/\/twitter.com\/hashtag\/Seahawks?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Seahawks<\/a> <a href=\"https:\/\/t.co\/UaStWijwWZ\">pic.twitter.com\/UaStWijwWZ<\/a><\/p>&mdash; EDFSPORTS NFL\ud83c\udfc8 (@edfsnfl) <a href=\"https:\/\/twitter.com\/edfsnfl\/status\/1539774875291815941?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 23, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Si bien termin\u00f3 disputando 14 de los 17 compromisos de los Browns, el mariscal de campo jug\u00f3 casi toda la ronda regular con molestias en el hombro derecho que lo llevaron a registrar sus peores n\u00fameros en la NFL y a someterse a una operaci\u00f3n el pasado mes de diciembre. <\/p>\n\n\n\n<p>En cuatro temporada en la NFL la primera escogencia global del Draft de 2018, por los Browns, tiene marca de 29-30 y <strong>en 2020 llev\u00f3 de regreso a Cleveland a la postemporada tras 17 a\u00f1os de sequ\u00eda<\/strong>. Adem\u00e1s, en cada una de esas campa\u00f1as ha llegado al menos a las 3.000 yardas para sumar 14.125, con 92 touchdowns, 56 pases de anotaci\u00f3n y un porcentaje de pases completos de 61.6%. <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQuedaste con ganas de m\u00e1s? S\u00edguenos en <a href=\"https:\/\/www.instagram.com\/jefebet\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram <\/a>y no te quedes sin saber todo lo nuevo del deporte y sus protagonistas, todo aqu\u00ed, en JefeBet.<\/strong><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Las puertas siguen m\u00e1s que abiertas para que Baker Mayfield pueda llegar en las pr\u00f3ximas semanas a los Seattle Seahawks. Seg\u00fan un reporte de la periodista Josina Anderson, de CBS Sports HQ, la organizaci\u00f3n sigue interesada en adquirir los servicios del mariscal de campo proveniente de los Cleveland Browns. Anderson agreg\u00f3 en su reporte que [&hellip;] <a class=\"g1-link g1-link-more\" href=\"https:\/\/blog.jefebet.com\/es\/noticias\/futbol-americano\/nfl\/baker-mayfield-nfl\/\">More<\/a><\/p>\n","protected":false},"author":15,"featured_media":66212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[39,20297,274],"tags":[19469,21281,505,20603],"reaction":[],"class_list":{"0":"post-66200","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nfl","8":"category-futbol-americano","9":"category-noticias","10":"tag-baker-mayfield","11":"tag-cleveland-browns","12":"tag-nfl","13":"tag-seattle-seahawks"},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts\/66200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/comments?post=66200"}],"version-history":[{"count":0,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/posts\/66200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/media\/66212"}],"wp:attachment":[{"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/media?parent=66200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/categories?post=66200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/tags?post=66200"},{"taxonomy":"reaction","embeddable":true,"href":"https:\/\/blog.jefebet.com\/es\/wp-json\/wp\/v2\/reaction?post=66200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}